{"id":2667,"date":"2023-10-13T14:18:26","date_gmt":"2023-10-13T14:18:26","guid":{"rendered":"https:\/\/doitall.com.mx\/?post_type=product&#038;p=2667"},"modified":"2024-02-08T04:13:13","modified_gmt":"2024-02-08T04:13:13","slug":"vuelo-en-paracaidas-punta-sam","status":"publish","type":"product","link":"https:\/\/amdlibertygroup.com\/index.php\/product\/vuelo-en-paracaidas-punta-sam\/","title":{"rendered":"VUELO EN PARACAIDAS (PUNTA SAM)"},"content":{"rendered":"<p>En esta experiencia los participantes podr\u00e1n disfrutar de una panor\u00e1mica a 80 metros de altura sobre la Zona Hotelera sin precedentes, la mejor vista de la Bah\u00eda de Canc\u00fan, Isla Mujeres y laguna Nichupte, combinado con las diferentes tonalidades color turquesa del mar caribe. Es un viaje en paraca\u00eddas seguro, c\u00f3modo y divertido para toda la familia. Una aventura realmente diferente, con Canc\u00fan bajo sus pies. La aventura comienza abordando un taxi acu\u00e1tico hacia la embarcaci\u00f3n dise\u00f1ada espec\u00edficamente para la actividad de paraca\u00eddas.<\/p>\n<p>Con una longitud de 30 pies, dicha embarcaci\u00f3n est\u00e1 equipada con una plataforma de despegue y aterrizaje desde la cual, disfrutar\u00e1 de un vuelo acariciando las alturas del cielo caribe\u00f1o volando libre a 80 metros de altura sobre las hermosas aguas cristalinas del mar caribe, con una duraci\u00f3n aproximada de 10 minutos en el aire.<\/p>\n<blockquote><p><strong><em>Panor\u00e1mica de Punta Sam:<\/em><\/strong><br \/>\nPara los vuelos de Parasail Canc\u00fan desde nuestra marina ubicada en Punta Sam, opera todos los d\u00edas de 9 a 10 minutos de vuelo efectivo m\u00e1s la transportaci\u00f3n mar\u00edtima a la embarcaci\u00f3n de despegue. El tiempo total de operaci\u00f3n para la actividad es de aproximadamente 30 minutos en total.<br \/>\nLos vuelos en nuestra marina de Punta Sam incluyen transportaci\u00f3n redonda con un tiempo aproximado de 45 minutos a una hora; hotel &#8211; Marina &#8211; hotel (tiempo de transporte seg\u00fan ubicaci\u00f3n del hotel).<\/p>\n<p>Contamos con 5 horarios todos los d\u00edas:<br \/>\n7:00 am, 9:00 am, 12:00 pm, 2:30 pm y 5:00 pm<\/p><\/blockquote>\n<p><strong><em>Bondades de la actividad:<\/em><\/strong><br \/>\nEs amigable con todo tipo de participantes: ni\u00f1os, adultos y tercera edad. No se requiere experiencia previa, ni vestimenta especial, solo el deseo de volar. No requiere ning\u00fan esfuerzo o saber nadar, el participante solo tiene que relajarse y disfrutar del vuelo, el staff de Parasail Canc\u00fan trabaja siempre sobre m\u00e1xima seguridad. El equipamiento de vuelo es de seguridad PREMIUM, \u00fanico en el mercado, cuidando todos los detalles, garant\u00eda de vuelo en todo momento, 100% seguro.<\/p>\n<p>El punto de partida est\u00e1 a solo 3 minutos de la embarcaci\u00f3n de despegue (sin mareos), vistas panor\u00e1micas de ensue\u00f1o, dif\u00edcil de olvidar. No hay restricciones en cuanto a c\u00e1maras, el participante puede tomar sus propias fotos en pleno vuelo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Restricciones:<\/em><\/strong><br \/>\n&#8211; Solo podr\u00e1n realizar la actividad ni\u00f1os de 10 a\u00f1os en adelante y con m\u00ednimo 1.35 metros de altura, acompa\u00f1ados por un adulto quien deber\u00e1 firmar las responsivas como padre o tutor.<br \/>\n&#8211; L\u00edmite de peso m\u00e1ximo: 180 kg, \/ 397 lb sean: 1,2 o 3 participantes.<br \/>\n&#8211; Peso m\u00ednimo: 29 kg \/65 lb<br \/>\n&#8211; No se permiten mujeres embarazadas.<br \/>\n&#8211; No se permiten participantes en estado de ebriedad o inconveniente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En esta experiencia los participantes podr\u00e1n disfrutar de una panor\u00e1mica a 80 metros de altura sobre la Zona Hotelera sin precedentes, la mejor vista de la Bah\u00eda de Canc\u00fan, Isla Mujeres y laguna Nichupte, combinado con las diferentes tonalidades color turquesa del mar caribe. Es un viaje en paraca\u00eddas seguro, c\u00f3modo y divertido para toda &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/amdlibertygroup.com\/index.php\/product\/vuelo-en-paracaidas-punta-sam\/\"> <span class=\"screen-reader-text\">VUELO EN PARACAIDAS (PUNTA SAM)<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"featured_media":2668,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"product_cat":[25,18,17],"product_tag":[],"_links":{"self":[{"href":"https:\/\/amdlibertygroup.com\/index.php\/wp-json\/wp\/v2\/product\/2667"}],"collection":[{"href":"https:\/\/amdlibertygroup.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/amdlibertygroup.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/amdlibertygroup.com\/index.php\/wp-json\/wp\/v2\/comments?post=2667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amdlibertygroup.com\/index.php\/wp-json\/wp\/v2\/media\/2668"}],"wp:attachment":[{"href":"https:\/\/amdlibertygroup.com\/index.php\/wp-json\/wp\/v2\/media?parent=2667"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/amdlibertygroup.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=2667"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/amdlibertygroup.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=2667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}